{"id":1144,"date":"2026-06-03T10:03:58","date_gmt":"2026-06-03T10:03:58","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/03\/sheinbaum-dice-no-somos-diaz-ordaz-y-promete-no-reprimir-a-la-cnte\/"},"modified":"2026-06-03T10:03:58","modified_gmt":"2026-06-03T10:03:58","slug":"sheinbaum-dice-no-somos-diaz-ordaz-y-promete-no-reprimir-a-la-cnte","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/03\/sheinbaum-dice-no-somos-diaz-ordaz-y-promete-no-reprimir-a-la-cnte\/","title":{"rendered":"Sheinbaum dice \u201cno somos D\u00edaz Ordaz\u201d y promete no reprimir a la CNTE"},"content":{"rendered":"<p>Este mi\u00e9rcoles 3 de junio, en su conferencia desde Palacio Nacional, Claudia Sheinbaum dej\u00f3 claro que no caer\u00e1 en provocaciones ni reprimir\u00e1 a la CNTE, pese a las protestas violentas que obligaron a cancelar la capacitaci\u00f3n de voluntarios del Fan Fest en el Z\u00f3calo.  <\/p>\n<p>La mandataria se\u00f1al\u00f3 que estas manifestaciones buscan desestabilizar justo antes del Mundial 2026 en CDMX, pero asegur\u00f3: \u201cNo somos D\u00edaz Ordaz\u201d. Adem\u00e1s, reiter\u00f3 que el di\u00e1logo con los maestros sigue abierto para resolver sus demandas sin violencia.  <\/p>\n<p>Esto es lo que necesitas saber: la protesta afect\u00f3 eventos oficiales, pero el gobierno apuesta por el orden sin represi\u00f3n, manteniendo la puerta abierta al di\u00e1logo. Mientras tanto, la atenci\u00f3n tambi\u00e9n est\u00e1 en el arancel del 10% a M\u00e9xico y Canad\u00e1 por trabajos forzados, otro tema que Sheinbaum abord\u00f3 hoy.  <\/p>\n<p>En un momento clave para la ciudad, donde proyectos como el cableb\u00fas buscan mejorar la movilidad, mantener la paz y el di\u00e1logo es la jugada para que todo siga en orden y sin m\u00e1s interrupciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles 3 de junio, en su conferencia desde Palacio Nacional, Claudia Sheinbaum dej\u00f3 claro que no caer\u00e1 en provocaciones ni reprimir\u00e1 a la CNTE, pese a las protestas violentas que obligaron a cancelar la capacitaci\u00f3n de voluntarios del Fan Fest en el Z\u00f3calo. La mandataria se\u00f1al\u00f3 que estas manifestaciones buscan desestabilizar justo antes del&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1144"}],"version-history":[{"count":0,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1143"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}