{"id":1200,"date":"2026-06-04T18:04:48","date_gmt":"2026-06-04T18:04:48","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/04\/explosion-en-tepeaca-no-es-ataque-de-eu-aclara-gobierno-de-puebla\/"},"modified":"2026-06-04T18:04:48","modified_gmt":"2026-06-04T18:04:48","slug":"explosion-en-tepeaca-no-es-ataque-de-eu-aclara-gobierno-de-puebla","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/04\/explosion-en-tepeaca-no-es-ataque-de-eu-aclara-gobierno-de-puebla\/","title":{"rendered":"Explosi\u00f3n en Tepeaca no es ataque de EU, aclara gobierno de Puebla"},"content":{"rendered":"<p>Este jueves 4 de junio de 2026, el gobierno de Puebla sali\u00f3 a desmentir un rumor que se viraliz\u00f3 en redes: que Estados Unidos estaba atacando a M\u00e9xico. La realidad es que el video que circula muestra la explosi\u00f3n de al menos cuatro pipas de gas LP en el municipio de Tepeaca, nada que ver con operaciones militares extranjeras.  <\/p>\n<p>La administraci\u00f3n de Alejandro Armenta dej\u00f3 claro que la cuenta &#8220;US Homeland Security News&#8221;, que difundi\u00f3 la informaci\u00f3n falsa, es ap\u00f3crifa y no tiene v\u00ednculo con ninguna instituci\u00f3n oficial.  <\/p>\n<p>Esto es lo que necesitas saber: no caigas en desinformaci\u00f3n, la explosi\u00f3n fue un accidente local y no un ataque. En tiempos donde la seguridad y el orden son clave, es vital confiar en datos oficiales y no en rumores que solo generan caos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 4 de junio de 2026, el gobierno de Puebla sali\u00f3 a desmentir un rumor que se viraliz\u00f3 en redes: que Estados Unidos estaba atacando a M\u00e9xico. La realidad es que el video que circula muestra la explosi\u00f3n de al menos cuatro pipas de gas LP en el municipio de Tepeaca, nada que ver&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1200"}],"version-history":[{"count":0,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1199"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}