{"id":1214,"date":"2026-06-05T09:45:20","date_gmt":"2026-06-05T09:45:20","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/05\/lego-lanza-su-set-mas-grande-la-sagrada-familia-en-12060-piezas\/"},"modified":"2026-06-05T09:45:20","modified_gmt":"2026-06-05T09:45:20","slug":"lego-lanza-su-set-mas-grande-la-sagrada-familia-en-12060-piezas","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/05\/lego-lanza-su-set-mas-grande-la-sagrada-familia-en-12060-piezas\/","title":{"rendered":"Lego lanza su set m\u00e1s grande: la Sagrada Familia en 12,060 piezas"},"content":{"rendered":"<p>\u00bfFan de Lego y la arquitectura? Ahora puedes armar la Sagrada Familia de Barcelona, el set m\u00e1s grande de la marca con 12,060 piezas y un precio de 17,999 pesos mexicanos (US$799.99). Este lanzamiento es parte de su colecci\u00f3n de monumentos ic\u00f3nicos y conmemora el centenario de la muerte de Antoni Gaud\u00ed.<\/p>\n<p>El modelo mide 62 cm de alto y reproduce detalles como el efecto de vidriera que hace \u00fanica a la bas\u00edlica real. Los pedidos anticipados ya est\u00e1n abiertos, pero la entrega ser\u00e1 hasta el 1 de noviembre.<\/p>\n<p>Dato cool: la Sagrada Familia, que empez\u00f3 a construirse en 1882, se consider\u00f3 imposible por su complejidad y la p\u00e9rdida de planos durante la Guerra Civil Espa\u00f1ola. Aunque Gaud\u00ed muri\u00f3 en 1926 con solo el 10-15% terminado, la obra sigue avanzando y la Torre de Jesucristo se termin\u00f3 en febrero de 2026. El papa Le\u00f3n XIV la inaugurar\u00e1 el pr\u00f3ximo mi\u00e9rcoles, justo 100 a\u00f1os despu\u00e9s de la muerte del arquitecto.<\/p>\n<p>Esto es lo que necesitas saber: un set para armar historia y arte, que celebra la visi\u00f3n de Gaud\u00ed y su legado que sigue vivo, pieza a pieza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfFan de Lego y la arquitectura? Ahora puedes armar la Sagrada Familia de Barcelona, el set m\u00e1s grande de la marca con 12,060 piezas y un precio de 17,999 pesos mexicanos (US$799.99). Este lanzamiento es parte de su colecci\u00f3n de monumentos ic\u00f3nicos y conmemora el centenario de la muerte de Antoni Gaud\u00ed. El modelo mide&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1214"}],"version-history":[{"count":0,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1213"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}