{"id":1370,"date":"2026-06-10T16:16:36","date_gmt":"2026-06-10T16:16:36","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/10\/armenta-revela-plan-para-renovar-transporte-en-puebla-con-8-mil-olinia-electricos\/"},"modified":"2026-06-10T16:16:36","modified_gmt":"2026-06-10T16:16:36","slug":"armenta-revela-plan-para-renovar-transporte-en-puebla-con-8-mil-olinia-electricos","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/10\/armenta-revela-plan-para-renovar-transporte-en-puebla-con-8-mil-olinia-electricos\/","title":{"rendered":"Armenta revela plan para renovar transporte en Puebla con 8 mil Olinia el\u00e9ctricos"},"content":{"rendered":"<p>Este mi\u00e9rcoles 10 de junio de 2026, el gobernador Alejandro Armenta dio detalles sobre la compra de 8 mil veh\u00edculos el\u00e9ctricos Olinia para Puebla, que arrancar\u00e1 en 2027 cuando inicie la producci\u00f3n comercial del proyecto impulsado por el Gobierno de M\u00e9xico.  <\/p>\n<p>Esto es lo que necesitas saber:<br \/>\n&#8211; 3 mil unidades ser\u00e1n para uso estatal, apoyando a Puebla Cinco de Mayo y al DIF.<br \/>\n&#8211; 5 mil veh\u00edculos reemplazar\u00e1n mototaxis y transporte convencional en varias regiones.  <\/p>\n<p>El plan busca darle un giro a la movilidad local, especialmente en municipios con alta presencia de mototaxis como Coronango, Acatzingo y Huaquechula, donde operan m\u00e1s de 5 mil 700 mototaxis, un servicio que ha generado problemas de seguridad y falta de regulaci\u00f3n.  <\/p>\n<p>El gobierno poblano apoyar\u00e1 a transportistas con un fondo que cubrir\u00e1 el 20% del enganche para que puedan adquirir estas unidades el\u00e9ctricas, que prometen ser una opci\u00f3n m\u00e1s segura, limpia y moderna.  <\/p>\n<p>El Olinia, presentado el pasado fin de semana por Claudia Sheinbaum, es el primer veh\u00edculo el\u00e9ctrico mexicano, con capacidad para seis pasajeros, autonom\u00eda de m\u00e1s de 125 km y un precio menor a 150 mil pesos. Adem\u00e1s, se puede cargar en enchufes comunes, facilitando su uso masivo.  <\/p>\n<p>Puebla tambi\u00e9n busca sumarse a la cadena de producci\u00f3n del Olinia, aprovechando su industria automotriz local.  <\/p>\n<p>Aunque la producci\u00f3n comercial inicia hasta verano de 2027 y hay retos como la infraestructura de recarga y la aceptaci\u00f3n de los transportistas, esta estrategia apunta a una transformaci\u00f3n real en la movilidad poblana, con un enfoque en transporte el\u00e9ctrico que, al igual que el Cableb\u00fas, apuesta por modernizar y ordenar el sistema de transporte p\u00fablico sin caer en intervenciones estatales excesivas.  <\/p>\n<p>La ruta est\u00e1 clara: primero fortalecer programas estatales con 3 mil Olinia y luego impulsar la renovaci\u00f3n del transporte p\u00fablico para dejar atr\u00e1s los mototaxis, mejorando la calidad y seguridad para todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles 10 de junio de 2026, el gobernador Alejandro Armenta dio detalles sobre la compra de 8 mil veh\u00edculos el\u00e9ctricos Olinia para Puebla, que arrancar\u00e1 en 2027 cuando inicie la producci\u00f3n comercial del proyecto impulsado por el Gobierno de M\u00e9xico. Esto es lo que necesitas saber: &#8211; 3 mil unidades ser\u00e1n para uso estatal,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1370"}],"version-history":[{"count":0,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1369"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}