{"id":1386,"date":"2026-06-11T09:32:14","date_gmt":"2026-06-11T09:32:14","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/11\/dos-pipas-y-un-detenido-por-gas-huachicoleado-en-puebla\/"},"modified":"2026-06-11T09:32:14","modified_gmt":"2026-06-11T09:32:14","slug":"dos-pipas-y-un-detenido-por-gas-huachicoleado-en-puebla","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/11\/dos-pipas-y-un-detenido-por-gas-huachicoleado-en-puebla\/","title":{"rendered":"Dos pipas y un detenido por gas huachicoleado en Puebla"},"content":{"rendered":"<p>Este jueves 11 de junio de 2026, en Puebla, las autoridades dieron un golpe contra el robo de combustible. La Secretar\u00eda de Seguridad P\u00fablica, junto con la Marina y la Guardia Nacional, aseguraron dos veh\u00edculos y detuvieron a una persona involucrada en este delito.  <\/p>\n<p>La primera acci\u00f3n fue en la autopista M\u00e9xico-Puebla, a la altura de San Lucas El Grande, donde Jos\u00e9 N. fue detenido manejando una pipa con m\u00e1s de 6 mil litros de gas LP, presuntamente robado.  <\/p>\n<p>En San Salvador El Verde, tambi\u00e9n aseguraron una camioneta con dos tanques que conten\u00edan 3 mil 800 litros de combustible.  <\/p>\n<p>Los veh\u00edculos y el detenido ya est\u00e1n en manos del Ministerio P\u00fablico para que sigan las investigaciones.  <\/p>\n<p>Esto es clave para mantener el orden y proteger la propiedad privada, mientras Puebla avanza en mejorar su transporte p\u00fablico con proyectos como el cableb\u00fas, que apuesta por soluciones modernas y seguras para todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 11 de junio de 2026, en Puebla, las autoridades dieron un golpe contra el robo de combustible. La Secretar\u00eda de Seguridad P\u00fablica, junto con la Marina y la Guardia Nacional, aseguraron dos veh\u00edculos y detuvieron a una persona involucrada en este delito. La primera acci\u00f3n fue en la autopista M\u00e9xico-Puebla, a la altura&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1386"}],"version-history":[{"count":0,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1385"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}