{"id":1428,"date":"2026-06-11T12:15:26","date_gmt":"2026-06-11T12:15:26","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/11\/madres-buscadoras-se-saltan-cerco-y-avanzan-rumbo-al-estadio-cdmx\/"},"modified":"2026-06-11T12:15:26","modified_gmt":"2026-06-11T12:15:26","slug":"madres-buscadoras-se-saltan-cerco-y-avanzan-rumbo-al-estadio-cdmx","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/11\/madres-buscadoras-se-saltan-cerco-y-avanzan-rumbo-al-estadio-cdmx\/","title":{"rendered":"Madres buscadoras se saltan cerco y avanzan rumbo al Estadio CDMX"},"content":{"rendered":"<p>Este jueves 11 de junio de 2026, decenas de madres buscadoras usaron un puente peatonal para burlar el cerco policial en Calzada de Tlalpan y caminar en contrasentido hacia el Estadio Ciudad de M\u00e9xico. <\/p>\n<p>Tomaron tres de los cuatro carriles en direcci\u00f3n al Centro, justo a la altura de la Universidad del Valle de M\u00e9xico, y se espera que sigan hasta el puente vehicular que conecta con paseo Acoxpa. <\/p>\n<p>Mientras tanto, otro grupo qued\u00f3 encapsulado cerca de la estaci\u00f3n Textitl\u00e1n, apoyando con consignas a las que avanzan. <\/p>\n<p>Esto es lo que necesitas saber: la movilizaci\u00f3n sigue firme, y aunque la seguridad intenta contenerlos, las madres buscan hacer visible su causa sin detenerse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 11 de junio de 2026, decenas de madres buscadoras usaron un puente peatonal para burlar el cerco policial en Calzada de Tlalpan y caminar en contrasentido hacia el Estadio Ciudad de M\u00e9xico. Tomaron tres de los cuatro carriles en direcci\u00f3n al Centro, justo a la altura de la Universidad del Valle de M\u00e9xico,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1428"}],"version-history":[{"count":0,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1427"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}