{"id":1496,"date":"2026-06-12T12:16:43","date_gmt":"2026-06-12T12:16:43","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/12\/la-florecita-la-loncheria-que-dice-adios-en-puebla-el-30-de-junio\/"},"modified":"2026-06-12T12:16:43","modified_gmt":"2026-06-12T12:16:43","slug":"la-florecita-la-loncheria-que-dice-adios-en-puebla-el-30-de-junio","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/12\/la-florecita-la-loncheria-que-dice-adios-en-puebla-el-30-de-junio\/","title":{"rendered":"La Florecita, la loncher\u00eda que dice adi\u00f3s en Puebla el 30 de junio"},"content":{"rendered":"<p>Puebla se prepara para despedir a La Florecita, la loncher\u00eda que durante m\u00e1s de 25 a\u00f1os fue parada obligada para tortas y desayunos cl\u00e1sicos. Este ic\u00f3nico lugar, que sobrevivi\u00f3 a la pandemia y a sus retos econ\u00f3micos, cerrar\u00e1 sus puertas definitivamente el pr\u00f3ximo 30 de junio.  <\/p>\n<p>\u00bfPor qu\u00e9 importa? Porque La Florecita no era solo comida, era un punto de encuentro para familias, estudiantes y trabajadores, con ese rollo tradicional que pocos lugares logran mantener. Su ambiente y sabor formaron parte de la identidad poblana, y ahora toca decirle adi\u00f3s.  <\/p>\n<p>Si eres de Puebla, tienes hasta el 30 de junio para darte una \u00faltima vuelta y disfrutar de esa loncher\u00eda que fue testigo de tantas historias. Un cierre que duele, pero que tambi\u00e9n nos recuerda la importancia de apoyar lo local y valorar lo que tenemos antes de que desaparezca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puebla se prepara para despedir a La Florecita, la loncher\u00eda que durante m\u00e1s de 25 a\u00f1os fue parada obligada para tortas y desayunos cl\u00e1sicos. Este ic\u00f3nico lugar, que sobrevivi\u00f3 a la pandemia y a sus retos econ\u00f3micos, cerrar\u00e1 sus puertas definitivamente el pr\u00f3ximo 30 de junio. \u00bfPor qu\u00e9 importa? Porque La Florecita no era solo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1495,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1496"}],"version-history":[{"count":0,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1495"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}