{"id":1612,"date":"2026-06-15T15:25:52","date_gmt":"2026-06-15T15:25:52","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/15\/estadounidense-detenido-en-bogota-por-presunto-abuso-a-nino-que-iba-a-adoptar\/"},"modified":"2026-06-15T21:25:53","modified_gmt":"2026-06-15T21:25:53","slug":"estadounidense-detenido-en-bogota-por-presunto-abuso-a-nino-que-iba-a-adoptar","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/15\/estadounidense-detenido-en-bogota-por-presunto-abuso-a-nino-que-iba-a-adoptar\/","title":{"rendered":"Estadounidense detenido en Bogot\u00e1 por presunto abuso a ni\u00f1o que iba a adoptar"},"content":{"rendered":"<p>El 14 de junio de 2026, en el norte de Bogot\u00e1, un ciudadano estadounidense fue detenido tras ser se\u00f1alado por presunto abuso sexual contra un menor que estaba en proceso de adopci\u00f3n.  <\/p>\n<p>Grant Gail, originario de Texas, estaba en la ciudad adelantando la adopci\u00f3n de tres ni\u00f1os. La alerta lleg\u00f3 cuando vecinos del sector Navarra, en Usaqu\u00e9n, vieron a un adulto con un ni\u00f1o en el balc\u00f3n de un apartamento y reportaron el hecho a la Polic\u00eda.  <\/p>\n<p>La Polic\u00eda Metropolitana, junto con la Dij\u00edn y la Polic\u00eda de Infancia y Adolescencia, ingres\u00f3 al lugar y encontr\u00f3 a tres menores de 4, 7 y 15 a\u00f1os. El ni\u00f1o de 7 a\u00f1os fue llevado al Hospital Sim\u00f3n Bol\u00edvar para valoraci\u00f3n m\u00e9dica, mientras que los otros dos quedaron bajo custodia de las autoridades.  <\/p>\n<p>El proceso de adopci\u00f3n se realizaba a trav\u00e9s de una entidad autorizada, confirm\u00f3 la directora del Icbf, Astrid C\u00e1ceres. Migraci\u00f3n Colombia inform\u00f3 que Grant Gail entr\u00f3 al pa\u00eds el 6 de junio por El Dorado sin alertas migratorias.  <\/p>\n<p>La Procuradur\u00eda, Fiscal\u00eda, Icbf y Polic\u00eda trabajan para proteger a los menores y garantizar que se restablezcan sus derechos. El alcalde Carlos Fernando Gal\u00e1n asegur\u00f3 que Bogot\u00e1 no tolerar\u00e1 ning\u00fan tipo de violencia o abuso contra ni\u00f1os.  <\/p>\n<p>Esto es lo que necesitas saber: un proceso de adopci\u00f3n que parec\u00eda avanzar se detuvo por una denuncia grave, y las autoridades est\u00e1n en alerta m\u00e1xima para proteger a los menores involucrados.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/Argenpoirot\/status\/2066370639565300045\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El 14 de junio de 2026, en el norte de Bogot\u00e1, un ciudadano estadounidense fue detenido tras ser se\u00f1alado por presunto abuso sexual contra un menor que estaba en proceso de adopci\u00f3n. Grant Gail, originario de Texas, estaba en la ciudad adelantando la adopci\u00f3n de tres ni\u00f1os. La alerta lleg\u00f3 cuando vecinos del sector Navarra,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1612"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1612\/revisions"}],"predecessor-version":[{"id":1613,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1612\/revisions\/1613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1611"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}