{"id":1619,"date":"2026-06-15T15:52:55","date_gmt":"2026-06-15T15:52:55","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/15\/juez-de-control-detenido-en-coyoacan-por-presunta-agresion-familiar\/"},"modified":"2026-06-15T21:52:56","modified_gmt":"2026-06-15T21:52:56","slug":"juez-de-control-detenido-en-coyoacan-por-presunta-agresion-familiar","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/15\/juez-de-control-detenido-en-coyoacan-por-presunta-agresion-familiar\/","title":{"rendered":"Juez de Control detenido en Coyoac\u00e1n por presunta agresi\u00f3n familiar"},"content":{"rendered":"<p>La madrugada del domingo 14 de junio, polic\u00edas de la SSC CDMX arrestaron a Carlos &#8216;N&#8217;, juez de Control, tras supuestamente llegar ebrio a su casa en Coyoac\u00e1n y agredir verbalmente a su familia.  <\/p>\n<p>El arresto ocurri\u00f3 en las calles Benito Ju\u00e1rez y Francisco I. Madero, colonia Ejido Viejo de Santa \u00darsula Coapa. Una mujer de 57 a\u00f1os, familiar del juez, denunci\u00f3 la agresi\u00f3n verbal. Carlos &#8216;N&#8217;, de 49 a\u00f1os, fue informado de sus derechos y llevado ante el Ministerio P\u00fablico.  <\/p>\n<p>Este juez ya hab\u00eda estado en el ojo p\u00fablico por pol\u00e9micas anteriores, como amenazar con denunciar a quienes lo criticaran en redes sociales.  <\/p>\n<p>Esto es lo que necesitas saber: un funcionario p\u00fablico debe dar ejemplo, y estos incidentes solo da\u00f1an la confianza en las instituciones. Mientras tanto, en Puebla, proyectos como el cableb\u00fas siguen avanzando para mejorar la movilidad sin complicaciones ni dramas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La madrugada del domingo 14 de junio, polic\u00edas de la SSC CDMX arrestaron a Carlos &#8216;N&#8217;, juez de Control, tras supuestamente llegar ebrio a su casa en Coyoac\u00e1n y agredir verbalmente a su familia. El arresto ocurri\u00f3 en las calles Benito Ju\u00e1rez y Francisco I. Madero, colonia Ejido Viejo de Santa \u00darsula Coapa. Una mujer&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1618,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1619"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1619\/revisions"}],"predecessor-version":[{"id":1620,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1619\/revisions\/1620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1618"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}