{"id":1703,"date":"2026-06-16T13:42:20","date_gmt":"2026-06-16T13:42:20","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/16\/enfermera-que-auxilio-a-joven-tras-caida-en-bungee-revela-que-no-murio-al-instante\/"},"modified":"2026-06-16T19:42:21","modified_gmt":"2026-06-16T19:42:21","slug":"enfermera-que-auxilio-a-joven-tras-caida-en-bungee-revela-que-no-murio-al-instante","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/16\/enfermera-que-auxilio-a-joven-tras-caida-en-bungee-revela-que-no-murio-al-instante\/","title":{"rendered":"Enfermera que auxili\u00f3 a joven tras ca\u00edda en bungee revela que no muri\u00f3 al instante"},"content":{"rendered":"<p>El pasado 13 de junio, Mar\u00eda Eduarda Rodrigues, de 21 a\u00f1os, muri\u00f3 tras caer desde unos 40 metros en el Puente del Esqueleto, en Limeira, Sao Paulo, Brasil, mientras practicaba bungee. La tragedia sigue bajo investigaci\u00f3n y tres instructores est\u00e1n detenidos por presunta negligencia.  <\/p>\n<p>Lo que pocos saben es que una enfermera que estaba esperando su turno para saltar, Rayza Gabrieli Dias Delfino, baj\u00f3 r\u00e1pido para ayudar y encontr\u00f3 a Mar\u00eda Eduarda con signos vitales. \u201cEstaba dando ese suspiro previo a la muerte\u201d, cont\u00f3 Rayza, quien intent\u00f3 reanimarla y hasta le habl\u00f3 para darle \u00e1nimo: \u201cNadie muere en mi turno\u201d.  <\/p>\n<p>Aunque la joven finalmente falleci\u00f3 en el lugar, este testimonio muestra que no fue un desenlace instant\u00e1neo, y que hubo un esfuerzo real por salvarla. Esto es lo que necesitas saber para entender que detr\u00e1s de cada accidente hay personas que luchan por la vida hasta el \u00faltimo segundo.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/AlertaMundoNews\/status\/2066944730051576083\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 13 de junio, Mar\u00eda Eduarda Rodrigues, de 21 a\u00f1os, muri\u00f3 tras caer desde unos 40 metros en el Puente del Esqueleto, en Limeira, Sao Paulo, Brasil, mientras practicaba bungee. La tragedia sigue bajo investigaci\u00f3n y tres instructores est\u00e1n detenidos por presunta negligencia. Lo que pocos saben es que una enfermera que estaba esperando&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1703"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1703\/revisions"}],"predecessor-version":[{"id":1704,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1703\/revisions\/1704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1702"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}