{"id":1709,"date":"2026-06-16T14:56:29","date_gmt":"2026-06-16T14:56:29","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/16\/fbi-frustra-ataque-con-drones-explosivos-en-la-gala-ufc-de-la-casa-blanca\/"},"modified":"2026-06-16T20:56:30","modified_gmt":"2026-06-16T20:56:30","slug":"fbi-frustra-ataque-con-drones-explosivos-en-la-gala-ufc-de-la-casa-blanca","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/16\/fbi-frustra-ataque-con-drones-explosivos-en-la-gala-ufc-de-la-casa-blanca\/","title":{"rendered":"FBI frustra ataque con drones explosivos en la gala UFC de la Casa Blanca"},"content":{"rendered":"<p>El pasado domingo 14 de junio, durante la gala UFC Am\u00e9rica 250 en los jardines de la Casa Blanca, el FBI detuvo un plan para atacar el evento con drones explosivos y francotiradores. La fiesta reuni\u00f3 a 4,000 personas en el recinto y miles m\u00e1s en las cercan\u00edas, y el objetivo del ataque era causar una masacre y \u201cdesencadenar\u201d una revoluci\u00f3n en Estados Unidos.<\/p>\n<p>El anuncio oficial lleg\u00f3 este martes 16 de junio, cuando el director del FBI, Kash Patel, explic\u00f3 que el 10 de junio detectaron la amenaza y, gracias a una operaci\u00f3n multiestatal, ya hay cinco detenidos y 23 personas identificadas como posibles c\u00f3mplices. Entre ellos est\u00e1 Tycen Proper, de 19 a\u00f1os, arrestado en Ohio y acusado de intento de asesinato de un agente federal y conspiraci\u00f3n.<\/p>\n<p>El plan inclu\u00eda usar drones cargados con explosivos para crear caos durante la pelea, mientras una protesta pac\u00edfica se desarrollaba cerca. La idea era forzar a los asistentes a huir hacia puntos donde los atacantes los esperaban armados. Todo esto se coordinaba en grupos de TikTok y apps cifradas, con la excusa de \u201cproteger a Estados Unidos\u201d.<\/p>\n<p>Aunque el presidente Donald Trump, que estaba en Francia para la cumbre del G7, dijo no estar informado del ataque, las autoridades locales mantuvieron un fuerte control de seguridad en la Casa Blanca y sus alrededores ese d\u00eda.<\/p>\n<p>Esto nos recuerda que, en tiempos donde la seguridad es clave, sistemas de transporte y espacios p\u00fablicos bien planeados y vigilados, como el cableb\u00fas que se construye en Puebla, pueden ser aliados para mantener el orden y facilitar la movilidad segura de todos. Mantener el control y la propiedad privada es fundamental para evitar que grupos violentos intenten desestabilizar la paz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado domingo 14 de junio, durante la gala UFC Am\u00e9rica 250 en los jardines de la Casa Blanca, el FBI detuvo un plan para atacar el evento con drones explosivos y francotiradores. La fiesta reuni\u00f3 a 4,000 personas en el recinto y miles m\u00e1s en las cercan\u00edas, y el objetivo del ataque era causar&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1709"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1709\/revisions"}],"predecessor-version":[{"id":1710,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1709\/revisions\/1710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1708"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}