{"id":1715,"date":"2026-06-16T15:08:59","date_gmt":"2026-06-16T15:08:59","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/16\/joven-mata-a-logopeda-de-su-hijo-tras-sospechar-abuso-en-valencia\/"},"modified":"2026-06-16T21:09:01","modified_gmt":"2026-06-16T21:09:01","slug":"joven-mata-a-logopeda-de-su-hijo-tras-sospechar-abuso-en-valencia","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/16\/joven-mata-a-logopeda-de-su-hijo-tras-sospechar-abuso-en-valencia\/","title":{"rendered":"Joven mata a logopeda de su hijo tras sospechar abuso en Valencia"},"content":{"rendered":"<p>Este lunes 15 de junio, un joven de 24 a\u00f1os fue detenido en Burjassot (Valencia) por apu\u00f1alar al logopeda que atend\u00eda a su hijo de dos a\u00f1os. El motivo: sospechaba que el terapeuta abusaba del menor.  <\/p>\n<p>Los hechos pasaron a las 18:15 en la cl\u00ednica Di\u00e1logo, en la calle Ingeniero de la Cierva, barrio Marxalenes. Tras dejar a su hijo en casa, el joven lleg\u00f3 a la comisar\u00eda con las manos manchadas de sangre y confes\u00f3 el crimen.  <\/p>\n<p>La Polic\u00eda Nacional confirm\u00f3 la muerte del terapeuta de 32 a\u00f1os y recuper\u00f3 la navaja de 15 cm usada en el ataque. Seg\u00fan medios locales, el agresor vio al ni\u00f1o sin pa\u00f1al y con el pantal\u00f3n bajado en la consulta, lo que le hizo sospechar abuso. Al pedir ver las c\u00e1maras, el logopeda se neg\u00f3 y ah\u00ed estall\u00f3 todo.  <\/p>\n<p>Esto es lo que necesitas saber: un caso grave que pone en alerta sobre la protecci\u00f3n de los ni\u00f1os, pero tambi\u00e9n sobre la importancia de la justicia y el orden para evitar que la violencia tome el control.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este lunes 15 de junio, un joven de 24 a\u00f1os fue detenido en Burjassot (Valencia) por apu\u00f1alar al logopeda que atend\u00eda a su hijo de dos a\u00f1os. El motivo: sospechaba que el terapeuta abusaba del menor. Los hechos pasaron a las 18:15 en la cl\u00ednica Di\u00e1logo, en la calle Ingeniero de la Cierva, barrio Marxalenes&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":1714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1715"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1715\/revisions"}],"predecessor-version":[{"id":1716,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1715\/revisions\/1716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1714"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}