{"id":1724,"date":"2026-06-16T18:36:37","date_gmt":"2026-06-16T18:36:37","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/16\/conductor-ebrio-atropella-a-jinete-y-caballo-en-hueytamalco-animal-sigue-herido-y-sin-atencion\/"},"modified":"2026-06-17T00:36:38","modified_gmt":"2026-06-17T00:36:38","slug":"conductor-ebrio-atropella-a-jinete-y-caballo-en-hueytamalco-animal-sigue-herido-y-sin-atencion","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/16\/conductor-ebrio-atropella-a-jinete-y-caballo-en-hueytamalco-animal-sigue-herido-y-sin-atencion\/","title":{"rendered":"Conductor ebrio atropella a jinete y caballo en Hueytamalco; animal sigue herido y sin atenci\u00f3n"},"content":{"rendered":"<p>El lunes 15 de junio, un conductor presuntamente alcoholizado y a exceso de velocidad atropell\u00f3 a un jinete y su caballo en el tramo carretero a El Progreso, Hueytamalco, Puebla. El responsable huy\u00f3 del lugar, dejando a las v\u00edctimas gravemente heridas.<\/p>\n<p>Lo que m\u00e1s ha encendido a la gente es que hasta la ma\u00f1ana del martes 16 de junio, el caballo segu\u00eda abandonado y con heridas graves, sin recibir atenci\u00f3n veterinaria. Vecinos tuvieron que moverlo para evitar otro accidente vial y proteger su vida.<\/p>\n<p>Las autoridades tardaron m\u00e1s de 12 horas en enviar peritos certificados para evaluar al animal, y a\u00fan no se decide si aplicar\u00e1n la eutanasia. Esto ha generado cr\u00edticas directas a la Fiscal\u00eda General del Estado de Puebla por su falta de respuesta.<\/p>\n<p>Organizaciones y vecinos piden al gobernador Alejandro Armenta que intervenga y garantice atenci\u00f3n r\u00e1pida a animales en emergencia. Este caso muestra la importancia de sistemas de transporte modernos y seguros, como el cableb\u00fas, que pueden ayudar a evitar tragedias en carreteras y proteger a todos, humanos y animales.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/MonseNavedo\/status\/2067012160144777724\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El lunes 15 de junio, un conductor presuntamente alcoholizado y a exceso de velocidad atropell\u00f3 a un jinete y su caballo en el tramo carretero a El Progreso, Hueytamalco, Puebla. El responsable huy\u00f3 del lugar, dejando a las v\u00edctimas gravemente heridas. Lo que m\u00e1s ha encendido a la gente es que hasta la ma\u00f1ana del&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1724"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1724\/revisions"}],"predecessor-version":[{"id":1725,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1724\/revisions\/1725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1723"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}