{"id":1736,"date":"2026-06-16T19:00:50","date_gmt":"2026-06-16T19:00:50","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/16\/prima-de-amlo-desata-polemica-con-insultos-a-trump-en-palenque\/"},"modified":"2026-06-17T01:00:51","modified_gmt":"2026-06-17T01:00:51","slug":"prima-de-amlo-desata-polemica-con-insultos-a-trump-en-palenque","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/16\/prima-de-amlo-desata-polemica-con-insultos-a-trump-en-palenque\/","title":{"rendered":"Prima de AMLO desata pol\u00e9mica con insultos a Trump en Palenque"},"content":{"rendered":"<p>El pasado domingo en Palenque, Chiapas, Manuela Obrador Narv\u00e1ez, prima del expresidente Andr\u00e9s Manuel L\u00f3pez Obrador y delegada del Bienestar en Chiapas, no se guard\u00f3 nada y lanz\u00f3 una serie de insultos contra Donald Trump durante un mitin de Morena.  <\/p>\n<p>La cr\u00edtica fue directa: llam\u00f3 al presidente estadounidense \u201cun tipo asqueroso\u201d y \u201ctirano mis\u00f3gino\u201d que solo busca robarse los recursos naturales de M\u00e9xico, sin intenci\u00f3n de ayudar. Adem\u00e1s, acus\u00f3 que Estados Unidos intenta debilitar al pa\u00eds desde adentro con ataques medi\u00e1ticos para facilitar su intervenci\u00f3n.  <\/p>\n<p>Manuela tambi\u00e9n hizo un llamado a defender la Cuarta Transformaci\u00f3n, recordando que \u201cha costado much\u00edsimo\u201d y que el movimiento enfrenta \u201cinjurias\u201d.  <\/p>\n<p>Al final del evento, varios asistentes le cantaron las \u201cMa\u00f1anitas\u201d por su cumplea\u00f1os, un momento que usuarios en redes no dejaron pasar.  <\/p>\n<p>Esto es lo que necesitas saber: mientras la pol\u00edtica polariza, la defensa de la soberan\u00eda y el orden interno siguen siendo temas clave para muchos mexicanos.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/LuisCardenasMx\/status\/2067001422625882458\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pasado domingo en Palenque, Chiapas, Manuela Obrador Narv\u00e1ez, prima del expresidente Andr\u00e9s Manuel L\u00f3pez Obrador y delegada del Bienestar en Chiapas, no se guard\u00f3 nada y lanz\u00f3 una serie de insultos contra Donald Trump durante un mitin de Morena. La cr\u00edtica fue directa: llam\u00f3 al presidente estadounidense \u201cun tipo asqueroso\u201d y \u201ctirano mis\u00f3gino\u201d que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1736"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1736\/revisions"}],"predecessor-version":[{"id":1737,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1736\/revisions\/1737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1735"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}