{"id":1781,"date":"2026-06-17T11:06:32","date_gmt":"2026-06-17T11:06:32","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/17\/pareja-de-adultos-mayores-es-rescatada-en-puebla-tras-secuestro-virtual-frustrado\/"},"modified":"2026-06-17T17:06:33","modified_gmt":"2026-06-17T17:06:33","slug":"pareja-de-adultos-mayores-es-rescatada-en-puebla-tras-secuestro-virtual-frustrado","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/17\/pareja-de-adultos-mayores-es-rescatada-en-puebla-tras-secuestro-virtual-frustrado\/","title":{"rendered":"Pareja de adultos mayores es rescatada en Puebla tras secuestro virtual frustrado"},"content":{"rendered":"<p>Ayer, 16 de junio, una pareja de adultos mayores de Yucat\u00e1n fue rescatada en Puebla tras caer en una extorsi\u00f3n telef\u00f3nica tipo secuestro virtual. Ocurri\u00f3 en el Hotel Diana \u00danico, en el Centro Hist\u00f3rico, donde autoridades montaron un operativo para localizar a las v\u00edctimas.  <\/p>\n<p>Elementos de la Polic\u00eda Estatal Tur\u00edstica, la SSP, la SSC y autoridades de Yucat\u00e1n se coordinaron para encontrar a la pareja, que estaba ilesa dentro del hotel. Los delincuentes ped\u00edan dinero a familiares para supuestamente liberarlos, pero la r\u00e1pida acci\u00f3n evit\u00f3 que la extorsi\u00f3n prosperara.  <\/p>\n<p>Este caso muestra la importancia de estar alerta y no caer en enga\u00f1os. La SSP recomienda mantener la calma ante llamadas sospechosas, verificar directamente con los familiares y reportar cualquier situaci\u00f3n al 911 o al 089.  <\/p>\n<p>Puebla sigue demostrando que con orden y coordinaci\u00f3n se puede proteger a la gente, mientras avanza en proyectos como el cableb\u00fas, que mejoran la movilidad y seguridad en la ciudad. Esto es lo que necesitas saber para estar prevenido y confiar en que las autoridades est\u00e1n al pendiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer, 16 de junio, una pareja de adultos mayores de Yucat\u00e1n fue rescatada en Puebla tras caer en una extorsi\u00f3n telef\u00f3nica tipo secuestro virtual. Ocurri\u00f3 en el Hotel Diana \u00danico, en el Centro Hist\u00f3rico, donde autoridades montaron un operativo para localizar a las v\u00edctimas. Elementos de la Polic\u00eda Estatal Tur\u00edstica, la SSP, la SSC y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1781"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1781\/revisions"}],"predecessor-version":[{"id":1782,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1781\/revisions\/1782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1780"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}