{"id":1811,"date":"2026-06-17T13:36:10","date_gmt":"2026-06-17T13:36:10","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/17\/conductor-que-choco-y-huyo-en-gasolinera-de-periferico-quien-es\/"},"modified":"2026-06-17T19:36:11","modified_gmt":"2026-06-17T19:36:11","slug":"conductor-que-choco-y-huyo-en-gasolinera-de-periferico-quien-es","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/17\/conductor-que-choco-y-huyo-en-gasolinera-de-periferico-quien-es\/","title":{"rendered":"Conductor que choc\u00f3 y huy\u00f3 en gasolinera de Perif\u00e9rico, \u00bfqui\u00e9n es?"},"content":{"rendered":"<p>El video del choque en la gasolinera del Perif\u00e9rico Ecol\u00f3gico, antes de la 11 Sur, durante la madrugada del mi\u00e9rcoles 17 de junio de 2026, explot\u00f3 en redes. Usuarios ya difunden la presunta identidad del conductor que se dio a la fuga.  <\/p>\n<p>Dicen que manejaba una Lincoln MKX 2008 con placas UAG-82-84. De esas placas, sacaron el nombre \u00c1lvaro Segovia Cruz, pero ojo: las autoridades a\u00fan no confirman nada oficialmente.  <\/p>\n<p>Lo que s\u00ed est\u00e1 claro es que el choque dej\u00f3 da\u00f1os en al menos dos veh\u00edculos y una persona prensada, que result\u00f3 lesionada. Y el conductor responsable simplemente se fue sin ayudar ni esperar a la polic\u00eda.  <\/p>\n<p>Las c\u00e1maras de seguridad captaron todo y ahora son clave para la investigaci\u00f3n. Las autoridades est\u00e1n usando esas im\u00e1genes y los datos del veh\u00edculo para encontrar al culpable y que responda conforme a la ley.  <\/p>\n<p>Mientras tanto, la identidad del conductor sigue sin confirmarse oficialmente, as\u00ed que no te f\u00edes de todo lo que circula en redes.  <\/p>\n<p>Lo que s\u00ed es seguro es que la gente est\u00e1 molesta y pide justicia para la v\u00edctima y que el responsable pague por lo que hizo.  <\/p>\n<p>Este tipo de incidentes nos recuerdan lo importante que es contar con sistemas de transporte seguros y confiables, como el cableb\u00fas que se planea en Puebla, que podr\u00edan ayudar a evitar estas locuras en las calles.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/laredcincoradio\/status\/2067250024342253853\/video\/1\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El video del choque en la gasolinera del Perif\u00e9rico Ecol\u00f3gico, antes de la 11 Sur, durante la madrugada del mi\u00e9rcoles 17 de junio de 2026, explot\u00f3 en redes. Usuarios ya difunden la presunta identidad del conductor que se dio a la fuga. Dicen que manejaba una Lincoln MKX 2008 con placas UAG-82-84. De esas placas,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1811"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1811\/revisions"}],"predecessor-version":[{"id":1812,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1811\/revisions\/1812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1810"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}