{"id":1856,"date":"2026-06-18T11:56:42","date_gmt":"2026-06-18T11:56:42","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/18\/sheinbaum-responde-a-trump-el-estado-mexicano-existe-y-no-ha-perdido-el-control-del-crimen\/"},"modified":"2026-06-18T17:56:42","modified_gmt":"2026-06-18T17:56:42","slug":"sheinbaum-responde-a-trump-el-estado-mexicano-existe-y-no-ha-perdido-el-control-del-crimen","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/18\/sheinbaum-responde-a-trump-el-estado-mexicano-existe-y-no-ha-perdido-el-control-del-crimen\/","title":{"rendered":"Sheinbaum responde a Trump: \u201cEl Estado mexicano existe\u201d y no ha perdido el control del crimen"},"content":{"rendered":"<p>Este jueves 18 de junio de 2026, Claudia Sheinbaum sali\u00f3 al quite tras las cr\u00edticas de Donald Trump sobre la seguridad en M\u00e9xico. La presidenta dej\u00f3 claro que el gobierno no ha perdido el control frente a los c\u00e1rteles y que las instituciones siguen trabajando con fuerza y coordinaci\u00f3n.  <\/p>\n<p>En su conferencia matutina, Sheinbaum dijo que Trump \u201cno est\u00e1 bien informado\u201d y que el Estado mexicano sigue firme con una estrategia activa para combatir la delincuencia. Destac\u00f3 la labor del gabinete de seguridad, con Omar Garc\u00eda Harfuch, Ricardo Trevilla y Raymundo Pedro Morales \u00c1ngeles al frente, y presumi\u00f3 resultados concretos: una baja del 46% en homicidios dolosos y m\u00e1s de 70% menos tr\u00e1fico de fentanilo hacia EU por tierra.  <\/p>\n<p>Adem\u00e1s, la mandataria subray\u00f3 la cooperaci\u00f3n con Estados Unidos para enfrentar delitos transnacionales y defendi\u00f3 la soberan\u00eda nacional ante las amenazas de revisar o cancelar el T-MEC. Asegur\u00f3 que M\u00e9xico mantiene una relaci\u00f3n econ\u00f3mica s\u00f3lida con su vecino del norte, con exportaciones en aumento y negociaciones para eliminar aranceles al acero.  <\/p>\n<p>Esto es lo que necesitas saber: Sheinbaum apuesta por el orden y la coordinaci\u00f3n para mejorar la seguridad, sin caer en confrontaciones personales, y mantiene firme la defensa de la soberan\u00eda y la econom\u00eda mexicana. Un mensaje claro para quienes dudan del Estado y su capacidad para proteger a la gente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 18 de junio de 2026, Claudia Sheinbaum sali\u00f3 al quite tras las cr\u00edticas de Donald Trump sobre la seguridad en M\u00e9xico. La presidenta dej\u00f3 claro que el gobierno no ha perdido el control frente a los c\u00e1rteles y que las instituciones siguen trabajando con fuerza y coordinaci\u00f3n. En su conferencia matutina, Sheinbaum dijo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1856"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1856\/revisions"}],"predecessor-version":[{"id":1857,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1856\/revisions\/1857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1855"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}