{"id":1907,"date":"2026-06-18T15:11:28","date_gmt":"2026-06-18T15:11:28","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/18\/ministra-de-la-scjn-arma-revuelo-por-decir-que-hoteles-all-inclusive-excluyen-a-mexicanos\/"},"modified":"2026-06-18T21:11:29","modified_gmt":"2026-06-18T21:11:29","slug":"ministra-de-la-scjn-arma-revuelo-por-decir-que-hoteles-all-inclusive-excluyen-a-mexicanos","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/18\/ministra-de-la-scjn-arma-revuelo-por-decir-que-hoteles-all-inclusive-excluyen-a-mexicanos\/","title":{"rendered":"Ministra de la SCJN arma revuelo por decir que hoteles \u201call inclusive\u201d excluyen a mexicanos"},"content":{"rendered":"<p>Este jueves 18 de junio de 2026, la ministra Loretta Ortiz Ahlf de la Suprema Corte de Justicia de la Naci\u00f3n se volvi\u00f3 tendencia por un comentario que dej\u00f3 a todos en shock y con ganas de memes. Durante una sesi\u00f3n del m\u00e1ximo tribunal, asegur\u00f3 que los hoteles \u201call inclusive\u201d no permiten la entrada a mexicanos y que solo est\u00e1n para extranjeros.  <\/p>\n<p>Obvio, la declaraci\u00f3n caus\u00f3 revuelo porque \u201call inclusive\u201d es un t\u00e9rmino b\u00e1sico en turismo que significa \u201ctodo incluido\u201d: pagas una tarifa y tienes hospedaje, comida, bebidas y m\u00e1s, sin importar si eres mexicano o extranjero.  <\/p>\n<p>Lo m\u00e1s curioso: mientras la ministra hablaba, alguien le pas\u00f3 una nota manuscrita para explicarle qu\u00e9 significa realmente \u201call inclusive\u201d. El video de ese momento se viraliz\u00f3 en X, Facebook y otras redes, y la gente no par\u00f3 de hacer memes y comentarios ir\u00f3nicos sobre la confusi\u00f3n.  <\/p>\n<p>Este episodio refleja c\u00f3mo las sesiones de la nueva Suprema Corte est\u00e1n siendo m\u00e1s vistas y comentadas que nunca, y pone en la mira la preparaci\u00f3n de algunos ministros. Hasta ahora, Loretta Ortiz no ha salido a aclarar nada.  <\/p>\n<p>Esto es lo que necesitas saber: los hoteles \u201call inclusive\u201d en M\u00e9xico, desde Canc\u00fan hasta Los Cabos, est\u00e1n abiertos para todos los que paguen, sin importar nacionalidad. As\u00ed que, si planeas tus vacaciones, no te preocupes, no te van a negar la entrada por ser mexicano. \ud83d\ude09<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/AleEsat\/status\/2067695556378710109\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 18 de junio de 2026, la ministra Loretta Ortiz Ahlf de la Suprema Corte de Justicia de la Naci\u00f3n se volvi\u00f3 tendencia por un comentario que dej\u00f3 a todos en shock y con ganas de memes. Durante una sesi\u00f3n del m\u00e1ximo tribunal, asegur\u00f3 que los hoteles \u201call inclusive\u201d no permiten la entrada a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1907"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1907\/revisions"}],"predecessor-version":[{"id":1908,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/1907\/revisions\/1908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/1906"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}