{"id":2117,"date":"2026-06-22T13:01:22","date_gmt":"2026-06-22T13:01:22","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/22\/madres-buscadoras-no-se-disfrazaron-de-pato-merlin-para-entrar-a-palacio-nacional\/"},"modified":"2026-06-22T19:01:22","modified_gmt":"2026-06-22T19:01:22","slug":"madres-buscadoras-no-se-disfrazaron-de-pato-merlin-para-entrar-a-palacio-nacional","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/22\/madres-buscadoras-no-se-disfrazaron-de-pato-merlin-para-entrar-a-palacio-nacional\/","title":{"rendered":"Madres buscadoras no se disfrazaron de \u201cPato Merl\u00edn\u201d para entrar a Palacio Nacional"},"content":{"rendered":"<p>En redes anda circulando una imagen que asegura que madres buscadoras se disfrazaron de botargas de pato con camisetas de la Selecci\u00f3n Mexicana para que Claudia Sheinbaum las recibiera en Palacio Nacional. Spoiler: es falso.  <\/p>\n<p>La foto real no es de ellas, sino de una activaci\u00f3n basada en el famoso \u201cPato Merl\u00edn\u201d, ese pato viral que se volvi\u00f3 s\u00edmbolo de la afici\u00f3n mexicana y que la jefa de gobierno invit\u00f3 a Palacio Nacional. Las botargas llevan el mismo outfit que el pato original, y las fichas de b\u00fasqueda que aparecen fueron puestas digitalmente o como parte de una protesta sat\u00edrica.  <\/p>\n<p>\u00bfPor qu\u00e9 sali\u00f3 este meme? Porque la invitaci\u00f3n a un animal viral para \u201cLa Ma\u00f1anera\u201d gener\u00f3 indignaci\u00f3n en redes, justo cuando las madres buscadoras enfrentan muchas trabas para ser recibidas por el Ejecutivo.  <\/p>\n<p>La realidad es que estas colectivas no usan disfraces para manifestarse; sus protestas son pac\u00edficas y solemnes, con fotos de sus hijos, misas y plantones afuera de Palacio.  <\/p>\n<p>Esto es lo que necesitas saber: la imagen es una s\u00e1tira que refleja una cr\u00edtica social real, pero no es verdad que las madres buscadoras hayan usado disfraces para protestar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En redes anda circulando una imagen que asegura que madres buscadoras se disfrazaron de botargas de pato con camisetas de la Selecci\u00f3n Mexicana para que Claudia Sheinbaum las recibiera en Palacio Nacional. Spoiler: es falso. La foto real no es de ellas, sino de una activaci\u00f3n basada en el famoso \u201cPato Merl\u00edn\u201d, ese pato viral&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2117"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2117\/revisions"}],"predecessor-version":[{"id":2118,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2117\/revisions\/2118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/2116"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}