{"id":2210,"date":"2026-06-23T10:13:50","date_gmt":"2026-06-23T10:13:50","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/23\/exfiscal-gertz-manero-revela-su-fortuna-13-propiedades-joyas-y-dos-rolls-royce\/"},"modified":"2026-06-23T16:13:52","modified_gmt":"2026-06-23T16:13:52","slug":"exfiscal-gertz-manero-revela-su-fortuna-13-propiedades-joyas-y-dos-rolls-royce","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/23\/exfiscal-gertz-manero-revela-su-fortuna-13-propiedades-joyas-y-dos-rolls-royce\/","title":{"rendered":"Exfiscal Gertz Manero revela su fortuna: 13 propiedades, joyas y dos Rolls-Royce"},"content":{"rendered":"<p>El pasado 15 de junio, Alejandro Gertz Manero, exfiscal general de la Rep\u00fablica, hizo p\u00fablica su declaraci\u00f3n patrimonial tras dejar la FGR y asumir como embajador de M\u00e9xico en Reino Unido. En el documento, que antes se manten\u00eda bajo reserva, report\u00f3 una colecci\u00f3n de bienes que incluye 13 inmuebles, joyas, obras de arte y hasta dos Rolls-Royce, adem\u00e1s de inversiones y cuentas bancarias en M\u00e9xico y el extranjero.<\/p>\n<p>Durante su gesti\u00f3n en la Fiscal\u00eda (enero 2019-noviembre 2025), Gertz mantuvo oculta esta informaci\u00f3n, pero ahora, obligado por su nuevo cargo en la Secretar\u00eda de Relaciones Exteriores, tuvo que transparentar su patrimonio. Entre sus propiedades hay 10 casas, un departamento, un terreno y un edificio, algunos heredados y otros comprados, como una casa adquirida en 1996 por 2.34 millones de pesos, un departamento en Madrid comprado en 2013 por un mill\u00f3n de euros y una vivienda en EU financiada con un cr\u00e9dito de 1.19 millones de d\u00f3lares.<\/p>\n<p>Su departamento en Madrid, ubicado en el barrio de Los Jer\u00f3nimos, ya hab\u00eda sido foco de atenci\u00f3n desde 2022, cuando El Pa\u00eds revel\u00f3 que posee propiedades en Espa\u00f1a valuadas en m\u00e1s de 100 millones de pesos. Adem\u00e1s, tiene participaciones en empresas mexicanas y espa\u00f1olas.<\/p>\n<p>En joyas y arte, declar\u00f3 piezas por m\u00e1s de 28 millones de pesos, y en autos, destaca una colecci\u00f3n de lujo y cl\u00e1sicos: un Cadillac 1994, un Mercedes-Benz 1979, un Rolls-Royce Sed\u00e1n 1966 y un Rolls-Royce Wraith 2014 comprado de contado en 2020 por 2.7 millones de pesos.<\/p>\n<p>Tambi\u00e9n report\u00f3 cuentas e inversiones en bancos como HSBC, BBVA, Scotiabank y Credit Suisse, y un cr\u00e9dito hipotecario con Chase Bank por m\u00e1s de 576 mil d\u00f3lares.<\/p>\n<p>Actualmente, su sueldo neto como embajador es de 196 mil pesos mensuales, sin ingresos extra por otras actividades. En 2025 declar\u00f3 ingresos por casi 2 millones de pesos.<\/p>\n<p>Esta revelaci\u00f3n llega tras a\u00f1os de cuestionamientos por la opacidad de su patrimonio y debates legales sobre su salida anticipada de la Fiscal\u00eda, aprobada por el Senado el 27 de noviembre de 2025, pese a que su periodo deb\u00eda terminar en 2028. Gertz justific\u00f3 su renuncia se\u00f1alando que la presidenta Claudia Sheinbaum le propuso la embajada, lo que le permitir\u00eda \u201ccontinuar sirviendo a mi pa\u00eds\u201d.<\/p>\n<p>Aunque la ley establece que la renuncia solo procede por causa grave, el Senado aval\u00f3 su salida y ratific\u00f3 su nuevo cargo en enero de 2026.<\/p>\n<p>Esto es lo que necesitas saber: Gertz Manero dej\u00f3 la Fiscal\u00eda con un patrimonio millonario y ahora representa a M\u00e9xico en Reino Unido, mientras sigue en el ojo p\u00fablico por la transparencia de sus bienes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 15 de junio, Alejandro Gertz Manero, exfiscal general de la Rep\u00fablica, hizo p\u00fablica su declaraci\u00f3n patrimonial tras dejar la FGR y asumir como embajador de M\u00e9xico en Reino Unido. En el documento, que antes se manten\u00eda bajo reserva, report\u00f3 una colecci\u00f3n de bienes que incluye 13 inmuebles, joyas, obras de arte y hasta&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2210"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2210\/revisions"}],"predecessor-version":[{"id":2211,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2210\/revisions\/2211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/2209"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}