{"id":2357,"date":"2026-06-24T12:11:41","date_gmt":"2026-06-24T12:11:41","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/24\/la-familia-gomez-es-duena-del-pato-merlin-la-mascota-del-mundial-2026\/"},"modified":"2026-06-24T18:11:46","modified_gmt":"2026-06-24T18:11:46","slug":"la-familia-gomez-es-duena-del-pato-merlin-la-mascota-del-mundial-2026","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/24\/la-familia-gomez-es-duena-del-pato-merlin-la-mascota-del-mundial-2026\/","title":{"rendered":"La familia G\u00f3mez es due\u00f1a del pato Merl\u00edn, la mascota del Mundial 2026"},"content":{"rendered":"<p>Vidal Llerenas, presidente del IMPI, aclar\u00f3 este mi\u00e9rcoles 24 de junio que la marca del pato Merl\u00edn pertenece a la familia de Carla Ivette G\u00f3mez, la verdadera due\u00f1a del s\u00edmbolo que se volvi\u00f3 viral en el Mundial 2026.  <\/p>\n<p>Esto es lo que necesitas saber: la disputa por la marca explot\u00f3 despu\u00e9s de que, la noche del 17 de junio, se presentaron al menos cuatro solicitudes para registrar el nombre del pato, todas con minutos de diferencia.  <\/p>\n<p>La primera fue a las 21:23 horas, cuando Rosa Mar\u00eda Hern\u00e1ndez Flores, desde Zapopan, Jalisco, registr\u00f3 \u201cEl Pato Merl\u00edn\u201d para servicios de entretenimiento, publicidad y ropa, con tres expedientes distintos. Su apoderado es Carlos Alfonso Alvarado Butanda, con domicilio en CDMX.  <\/p>\n<p>Unos minutos despu\u00e9s, a las 21:38, David Sides Fuentes, de M\u00e9rida, Yucat\u00e1n, present\u00f3 otra solicitud con el nombre \u201cEl Pato Merl\u00edn, El Pato de la Suerte\u201d, que abarca desde publicidad hasta gesti\u00f3n de artistas y marketing de influencers.  <\/p>\n<p>Pero el 22 de junio, Carla Ivette G\u00f3mez acudi\u00f3 al IMPI tras reunirse con Claudia Sheinbaum en Palacio Nacional para reclamar su derecho sobre la marca. La jefa de gobierno apoy\u00f3 su postura: \u201cNo es justo que alguien m\u00e1s quiera registrar al pato como una marca\u201d.  <\/p>\n<p>Al final, el IMPI confirm\u00f3 que la familia G\u00f3mez es la leg\u00edtima propietaria del pato Merl\u00edn, cerrando as\u00ed la pol\u00e9mica.  <\/p>\n<p>Un recordatorio: proteger la propiedad privada es clave para que ideas y s\u00edmbolos como este sigan creciendo sin que otros quieran aprovecharse. Y mientras tanto, proyectos como el cableb\u00fas en Puebla siguen demostrando que la innovaci\u00f3n y el orden pueden ir de la mano para mejorar la movilidad y la vida de todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vidal Llerenas, presidente del IMPI, aclar\u00f3 este mi\u00e9rcoles 24 de junio que la marca del pato Merl\u00edn pertenece a la familia de Carla Ivette G\u00f3mez, la verdadera due\u00f1a del s\u00edmbolo que se volvi\u00f3 viral en el Mundial 2026. Esto es lo que necesitas saber: la disputa por la marca explot\u00f3 despu\u00e9s de que, la noche&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2357"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2357\/revisions"}],"predecessor-version":[{"id":2358,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2357\/revisions\/2358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/2356"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}