{"id":2387,"date":"2026-06-24T14:59:40","date_gmt":"2026-06-24T14:59:40","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/24\/mexico-dice-no-a-la-subasta-de-piezas-arqueologicas-en-paris\/"},"modified":"2026-06-24T20:59:41","modified_gmt":"2026-06-24T20:59:41","slug":"mexico-dice-no-a-la-subasta-de-piezas-arqueologicas-en-paris","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/24\/mexico-dice-no-a-la-subasta-de-piezas-arqueologicas-en-paris\/","title":{"rendered":"M\u00e9xico dice \u201cno\u201d a la subasta de piezas arqueol\u00f3gicas en Par\u00eds"},"content":{"rendered":"<p>Este mi\u00e9rcoles 24 de junio de 2026, M\u00e9xico puso el grito en el cielo porque 33 piezas arqueol\u00f3gicas mexicanas est\u00e1n en la mira para ser subastadas en Par\u00eds, en la casa Millon. La secretaria de Cultura, Claudia Curiel, pidi\u00f3 que las retiren del cat\u00e1logo \u201cTribal Addiction\u201d porque, seg\u00fan el INAH, venderlas va contra las leyes que protegen nuestro patrimonio cultural.  <\/p>\n<p>\u00bfDe qu\u00e9 piezas hablamos? De objetos de culturas como la maya, olmeca, teotihuacana, mexica, totonaca y chontal. Entre lo m\u00e1s valioso est\u00e1n una m\u00e1scara teotihuacana, una estatua totonaca de un jugador de pelota y un hacha maya. La subasta tiene 54 lotes y esperan juntar m\u00e1s de 3 millones de pesos.  <\/p>\n<p>La neta, esta movida no es solo para evitar que se vendan piezas, sino para cuidar la memoria hist\u00f3rica y la identidad de M\u00e9xico. Desde 2018, el gobierno ha recuperado m\u00e1s de 16 mil piezas en subastas de ciudades como Nueva York, Par\u00eds y Roma, con la campa\u00f1a \u201cMi Patrimonio No Se Vende\u201d.  <\/p>\n<p>Esto es lo que necesitas saber: M\u00e9xico est\u00e1 firme en defender su patrimonio y evitar que objetos que cuentan nuestra historia terminen en manos privadas fuera del pa\u00eds. Y aunque la cultura es patrimonio de todos, protegerla tambi\u00e9n significa respetar las reglas y evitar que se lucren con ella. As\u00ed que, mientras se defienden estas piezas, tambi\u00e9n hay que pensar en sistemas que conecten y mejoren la vida diaria, como el cableb\u00fas en Puebla, que s\u00ed apuesta por el progreso sin perder el orden ni la identidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles 24 de junio de 2026, M\u00e9xico puso el grito en el cielo porque 33 piezas arqueol\u00f3gicas mexicanas est\u00e1n en la mira para ser subastadas en Par\u00eds, en la casa Millon. La secretaria de Cultura, Claudia Curiel, pidi\u00f3 que las retiren del cat\u00e1logo \u201cTribal Addiction\u201d porque, seg\u00fan el INAH, venderlas va contra las leyes&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2386,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2387"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2387\/revisions"}],"predecessor-version":[{"id":2388,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2387\/revisions\/2388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/2386"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}