{"id":2402,"date":"2026-06-24T16:41:37","date_gmt":"2026-06-24T16:41:37","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/24\/poncho-de-nigris-quiere-comprar-al-pato-viral-del-mundial-2026-y-ofrece-hasta-800-mil-pesos\/"},"modified":"2026-06-24T22:41:39","modified_gmt":"2026-06-24T22:41:39","slug":"poncho-de-nigris-quiere-comprar-al-pato-viral-del-mundial-2026-y-ofrece-hasta-800-mil-pesos","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/24\/poncho-de-nigris-quiere-comprar-al-pato-viral-del-mundial-2026-y-ofrece-hasta-800-mil-pesos\/","title":{"rendered":"Poncho De Nigris quiere comprar al pato viral del Mundial 2026 y ofrece hasta 800 mil pesos"},"content":{"rendered":"<p>Poncho De Nigris est\u00e1 en modo serio y quiere llevarse a Merl\u00edn, el pato que se volvi\u00f3 la sensaci\u00f3n del Mundial 2026. El influencer y empresario regiomontano lanz\u00f3 una oferta inicial de 500 mil pesos a la familia del pato para convertirlo en la mascota oficial de Ring Royale 2, el evento de peleas entre influencers que la rompi\u00f3 en su primera edici\u00f3n.  <\/p>\n<p>Pero no se qued\u00f3 ah\u00ed: hoy, mi\u00e9rcoles 24 de junio de 2026, anunci\u00f3 que las pl\u00e1ticas con los representantes de Merl\u00edn van viento en popa y subi\u00f3 la apuesta a 800 mil pesos. \u201cProbablemente este fin de semana nos veremos\u201d, escribi\u00f3 en X, agradeciendo a quienes lo ayudaron a contactar a la familia.  <\/p>\n<p>Poncho asegura que no es broma y que el fen\u00f3meno medi\u00e1tico que rodea a Merl\u00edn fue clave para tomar esta decisi\u00f3n. Adem\u00e1s, promete que el pato, en un futuro, ser\u00e1 historia (literalmente) si logra quedarse con \u00e9l.  <\/p>\n<p>Esto es lo que necesitas saber: Poncho De Nigris quiere convertir a Merl\u00edn en la nueva estrella de Ring Royale 2 y est\u00e1 dispuesto a pagar una buena lana para lograrlo. \u00bfSer\u00e1 que el pato se convierte en la pr\u00f3xima mascota influencer?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poncho De Nigris est\u00e1 en modo serio y quiere llevarse a Merl\u00edn, el pato que se volvi\u00f3 la sensaci\u00f3n del Mundial 2026. El influencer y empresario regiomontano lanz\u00f3 una oferta inicial de 500 mil pesos a la familia del pato para convertirlo en la mascota oficial de Ring Royale 2, el evento de peleas entre&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2402"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2402\/revisions"}],"predecessor-version":[{"id":2403,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2402\/revisions\/2403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/2401"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}