{"id":2507,"date":"2026-06-25T15:13:03","date_gmt":"2026-06-25T15:13:03","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/25\/pastor-da-golpiza-a-vecino-que-amenazo-a-su-familia-en-louisiana\/"},"modified":"2026-06-25T21:13:06","modified_gmt":"2026-06-25T21:13:06","slug":"pastor-da-golpiza-a-vecino-que-amenazo-a-su-familia-en-louisiana","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/25\/pastor-da-golpiza-a-vecino-que-amenazo-a-su-familia-en-louisiana\/","title":{"rendered":"Pastor da golpiza a vecino que amenaz\u00f3 a su familia en Louisiana"},"content":{"rendered":"<p>El martes 23 de junio, Tony Spell, pastor de 48 a\u00f1os de la iglesia Life Tabernacle Church en Baton Rouge, Louisiana, se meti\u00f3 en tremendo l\u00edo tras darle una paliza al hijo de su vecino. \u00bfLa raz\u00f3n? El joven de 20 a\u00f1os le lanz\u00f3 amenazas bien pesadas: dijo que iba a violar a la esposa de Spell, a sus nietos y que los matar\u00eda cuando \u00e9l no estuviera.  <\/p>\n<p>Spell, que estaba cambiando la bater\u00eda de los micros escolares de su iglesia, no se qued\u00f3 callado y cruz\u00f3 la calle para enfrentar al muchacho frente a la iglesia, con autos pasando y todo. El video de seguridad muestra c\u00f3mo el pastor le dio 8 golpes de pie y luego 27 m\u00e1s en el suelo, adem\u00e1s de torcerle el cuello y patearlo. El joven termin\u00f3 con cinco puntos de sutura en el ment\u00f3n.  <\/p>\n<p>El pastor dijo que actu\u00f3 por \u201cdeber y obligaci\u00f3n\u201d para proteger a su familia: \u201cPrimero soy esposo, despu\u00e9s padre y, en tercer lugar, pastor que cuida a su reba\u00f1o\u201d. La polic\u00eda lo arrest\u00f3 y lo acusa de agresi\u00f3n en segundo grado, que podr\u00eda costarle hasta ocho a\u00f1os en la c\u00e1rcel. Spell tiene que presentarse ante la justicia el 15 de septiembre y asegura que \u201cla verdad saldr\u00e1 en el tribunal\u201d.  <\/p>\n<p>Este conflicto no es nuevo: Spell y la familia Sherwin llevan a\u00f1os en disputa, incluso con demandas y pol\u00e9micas previas, como cuando el pastor fue multado por hacer servicios presenciales en plena pandemia y acusado de agredir a un manifestante (aunque no fue imputado).  <\/p>\n<p>Despu\u00e9s de la pelea, Spell habl\u00f3 con su congregaci\u00f3n y compar\u00f3 la situaci\u00f3n con \u201cterrorismo dom\u00e9stico\u201d, citando la Biblia y diciendo que \u201cpuso las manos sobre el enfermo\u201d, refiri\u00e9ndose a su agresi\u00f3n.  <\/p>\n<p>Este caso volvi\u00f3 a poner en el ojo p\u00fablico a Spell, un pastor que no se anda con medias tintas y que defiende a capa y espada a su familia y su iglesia. \u00bfJusticia o exceso? T\u00fa decides.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/CollinRugg\/status\/2069893607323320781\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El martes 23 de junio, Tony Spell, pastor de 48 a\u00f1os de la iglesia Life Tabernacle Church en Baton Rouge, Louisiana, se meti\u00f3 en tremendo l\u00edo tras darle una paliza al hijo de su vecino. \u00bfLa raz\u00f3n? El joven de 20 a\u00f1os le lanz\u00f3 amenazas bien pesadas: dijo que iba a violar a la esposa&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2507"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2507\/revisions"}],"predecessor-version":[{"id":2508,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2507\/revisions\/2508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/2506"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}