{"id":2528,"date":"2026-06-26T10:09:31","date_gmt":"2026-06-26T10:09:31","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/26\/mas-de-270-mil-personas-vibraron-con-alejandro-fernandez-en-la-minerva\/"},"modified":"2026-06-26T16:09:32","modified_gmt":"2026-06-26T16:09:32","slug":"mas-de-270-mil-personas-vibraron-con-alejandro-fernandez-en-la-minerva","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/26\/mas-de-270-mil-personas-vibraron-con-alejandro-fernandez-en-la-minerva\/","title":{"rendered":"M\u00e1s de 270 mil personas vibraron con Alejandro Fern\u00e1ndez en La Minerva"},"content":{"rendered":"<p>La noche del jueves 25 de junio, La Minerva y sus alrededores en Guadalajara se llenaron de m\u00fasica y energ\u00eda con \u201cLa serenata m\u00e1s grande del mundo\u201d. M\u00e1s de 270 mil personas llegaron para el concierto gratuito de Alejandro Fern\u00e1ndez, que calent\u00f3 motores para el partido Espa\u00f1a vs Uruguay del Mundial 2026, programado para este viernes 26 de junio a las 18:00 horas en el Estadio Akron.  <\/p>\n<p>No solo \u201cEl Potrillo\u201d prendi\u00f3 el escenario, tambi\u00e9n sus hijos Camila y Alex Fern\u00e1ndez, junto a Juli\u00f3n \u00c1lvarez y Alfredo Olivas, quienes pusieron a cantar a casi 300 mil almas con sus mejores \u00e9xitos.  <\/p>\n<p>Protecci\u00f3n Civil Jalisco report\u00f3 que a las 18:00 horas hab\u00eda 60 mil asistentes, pero para las 23:00 la cifra ya superaba las 270 mil.  <\/p>\n<p>Este evento no solo fue un show, sino una forma de mostrar al mundo la esencia mexicana que Jalisco quiere proyectar como sede del Mundial 2026. Y s\u00ed, mientras la ciudad se llena de gente y m\u00fasica, tambi\u00e9n es clave pensar en opciones de transporte eficientes y modernas, como el cableb\u00fas o telef\u00e9rico, que podr\u00edan ayudar a mover a tanta gente sin caos ni broncas. \u00a1As\u00ed se hace!<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/Rhevolver\/status\/2070365884263153847\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La noche del jueves 25 de junio, La Minerva y sus alrededores en Guadalajara se llenaron de m\u00fasica y energ\u00eda con \u201cLa serenata m\u00e1s grande del mundo\u201d. M\u00e1s de 270 mil personas llegaron para el concierto gratuito de Alejandro Fern\u00e1ndez, que calent\u00f3 motores para el partido Espa\u00f1a vs Uruguay del Mundial 2026, programado para este&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2527,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2528"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2528\/revisions"}],"predecessor-version":[{"id":2529,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2528\/revisions\/2529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/2527"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}