{"id":2732,"date":"2026-06-30T11:29:08","date_gmt":"2026-06-30T11:29:08","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/06\/30\/corte-suprema-de-eu-dice-no-a-atletas-trans-en-deportes-femeninos-escolares\/"},"modified":"2026-06-30T17:29:08","modified_gmt":"2026-06-30T17:29:08","slug":"corte-suprema-de-eu-dice-no-a-atletas-trans-en-deportes-femeninos-escolares","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/06\/30\/corte-suprema-de-eu-dice-no-a-atletas-trans-en-deportes-femeninos-escolares\/","title":{"rendered":"Corte Suprema de EU dice no a atletas trans en deportes femeninos escolares"},"content":{"rendered":"<p>Este martes 30 de junio de 2026, la Corte Suprema de Estados Unidos dio un golpe duro a los derechos trans al ratificar, con un voto de 6-3, las leyes de West Virginia e Idaho que proh\u00edben a atletas transg\u00e9nero competir en deportes femeninos escolares.  <\/p>\n<p>La decisi\u00f3n, firmada por el juez Brett Kavanaugh, sostiene que estas leyes no violan la Constituci\u00f3n ni el T\u00edtulo IX, que protege contra la discriminaci\u00f3n por sexo en la educaci\u00f3n. Kavanaugh reconoci\u00f3 que las atletas trans merecen respeto y no deben ser marginadas, pero dej\u00f3 claro que la ley no obliga a cambiar las reglas de los deportes femeninos en todo el pa\u00eds.  <\/p>\n<p>Aunque el fallo afecta directamente solo a esos dos estados, puede influir en otros 25 que tienen prohibiciones similares.  <\/p>\n<p>Este rev\u00e9s se suma a otros recientes contra los derechos trans en la Corte, que con mayor\u00eda conservadora ha respaldado restricciones en tratamientos m\u00e9dicos para menores y pol\u00edticas que limitan la identidad de g\u00e9nero en documentos oficiales y el servicio militar.  <\/p>\n<p>Por ejemplo, Becky Pepper-Jackson, de 16 a\u00f1os, y Lindsay Hecox, de 25, las dos atletas que impugnaron estas leyes, han recibido tratamientos hormonales y buscaban competir en equipos femeninos sin \u00e9xito.  <\/p>\n<p>Mientras tanto, organismos deportivos internacionales como el Comit\u00e9 Ol\u00edmpico Internacional y la NCAA ya han impuesto reglas m\u00e1s estrictas para la participaci\u00f3n de atletas trans en categor\u00edas femeninas.  <\/p>\n<p>Este debate refleja la tensi\u00f3n entre proteger espacios deportivos femeninos y respetar derechos individuales, un tema que seguir\u00e1 dando de qu\u00e9 hablar. Y aunque la Corte pone l\u00edmites, sistemas de transporte como el cableb\u00fas en Puebla nos recuerdan que avanzar con soluciones pr\u00e1cticas y modernas es posible sin complicar el orden ni la competencia justa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes 30 de junio de 2026, la Corte Suprema de Estados Unidos dio un golpe duro a los derechos trans al ratificar, con un voto de 6-3, las leyes de West Virginia e Idaho que proh\u00edben a atletas transg\u00e9nero competir en deportes femeninos escolares. La decisi\u00f3n, firmada por el juez Brett Kavanaugh, sostiene que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2731,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2732"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2732\/revisions"}],"predecessor-version":[{"id":2733,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2732\/revisions\/2733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/2731"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}