{"id":2945,"date":"2026-07-02T09:53:30","date_gmt":"2026-07-02T09:53:30","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/07\/02\/messi-sin-privilegios-en-filtro-de-seguridad-antes-del-partido-vs-cabo-verde\/"},"modified":"2026-07-02T15:53:35","modified_gmt":"2026-07-02T15:53:35","slug":"messi-sin-privilegios-en-filtro-de-seguridad-antes-del-partido-vs-cabo-verde","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/07\/02\/messi-sin-privilegios-en-filtro-de-seguridad-antes-del-partido-vs-cabo-verde\/","title":{"rendered":"Messi sin privilegios en filtro de seguridad antes del partido vs Cabo Verde"},"content":{"rendered":"<p>Este jueves 2 de julio, Lionel Messi demostr\u00f3 que ni siendo la estrella del Mundial 2026 se salva de pasar por el filtro de seguridad como todos los dem\u00e1s. En un aeropuerto de Estados Unidos, el crack argentino tuvo que dejar sus cosas, sentarse y pasar el detector de metales en las suelas de sus tenis y en todo el cuerpo, sin trato VIP ni atajos.<\/p>\n<p>Un video que se viraliz\u00f3 muestra el momento en que Messi, con una sonrisa, observa lo que lleva su compa\u00f1ero Cristian Romero, lo que desat\u00f3 risas entre ellos. Nada de privilegios, solo un recordatorio de que en el Mundial todos est\u00e1n en igualdad de condiciones.<\/p>\n<p>Por cierto, Messi y Kylian Mbapp\u00e9 est\u00e1n empatados como l\u00edderes de goleo con seis goles cada uno, justo antes del duelo de Argentina contra Cabo Verde en los Dieciseisavos de final que se jugar\u00e1 este viernes. El argentino sigue siendo el m\u00e1ximo goleador en la historia de los Mundiales con 19 anotaciones desde 2006, seguido muy de cerca por Mbapp\u00e9 con 18.<\/p>\n<p>Esto es lo que necesitas saber: Messi no solo brilla en la cancha, tambi\u00e9n en la humildad para pasar los controles. Y ojo, que el Mundial 2026 est\u00e1 que arde.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/lopezdoriga\/status\/2072676162375995724\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 2 de julio, Lionel Messi demostr\u00f3 que ni siendo la estrella del Mundial 2026 se salva de pasar por el filtro de seguridad como todos los dem\u00e1s. En un aeropuerto de Estados Unidos, el crack argentino tuvo que dejar sus cosas, sentarse y pasar el detector de metales en las suelas de sus&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2944,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2945"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2945\/revisions"}],"predecessor-version":[{"id":2946,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/2945\/revisions\/2946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/2944"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}