{"id":3093,"date":"2026-07-03T11:54:08","date_gmt":"2026-07-03T11:54:08","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/07\/03\/habra-puente-o-home-office-el-lunes-6-de-julio-tras-mexico-vs-inglaterra-en-el-mundial-2026\/"},"modified":"2026-07-03T17:54:10","modified_gmt":"2026-07-03T17:54:10","slug":"habra-puente-o-home-office-el-lunes-6-de-julio-tras-mexico-vs-inglaterra-en-el-mundial-2026","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/07\/03\/habra-puente-o-home-office-el-lunes-6-de-julio-tras-mexico-vs-inglaterra-en-el-mundial-2026\/","title":{"rendered":"\u00bfHabr\u00e1 puente o home office el lunes 6 de julio tras M\u00e9xico vs Inglaterra en el Mundial 2026?"},"content":{"rendered":"<p>El partido de octavos de final entre M\u00e9xico e Inglaterra ser\u00e1 el domingo 5 de julio a las 18:00 horas en el Estadio Azteca, y ya tiene a todos al filo del asiento. Pero, \u00bfqu\u00e9 pasa con el lunes 6? \u00bfSe suspenden clases o se trabaja desde casa?  <\/p>\n<p>La respuesta corta: no. Ni el Gobierno federal ni los estados han anunciado asueto, suspensi\u00f3n de clases o home office para ese d\u00eda. As\u00ed que el lunes 6 de julio toca volver a la rutina normal: escuela, chamba y bancos funcionando como siempre.  <\/p>\n<p>Eso s\u00ed, en partidos anteriores del Mundial 2026, en ciudades como CDMX, Guadalajara y Monterrey s\u00ed se suspendieron clases y se aplic\u00f3 home office para funcionarios p\u00fablicos en d\u00edas de partido. Pero para este duelo clave en la capital, todo apunta a que no habr\u00e1 puente ni descanso oficial.  <\/p>\n<p>Esto es lo que necesitas saber: el domingo 5 de julio el pa\u00eds se paraliza para apoyar a la selecci\u00f3n, pero el lunes 6 toca regresar al orden y la productividad sin pretextos. \u00a1A darle con todo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El partido de octavos de final entre M\u00e9xico e Inglaterra ser\u00e1 el domingo 5 de julio a las 18:00 horas en el Estadio Azteca, y ya tiene a todos al filo del asiento. Pero, \u00bfqu\u00e9 pasa con el lunes 6? \u00bfSe suspenden clases o se trabaja desde casa? La respuesta corta: no. Ni el Gobierno&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3093"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3093\/revisions"}],"predecessor-version":[{"id":3094,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3093\/revisions\/3094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/3092"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}