{"id":3132,"date":"2026-07-03T14:08:17","date_gmt":"2026-07-03T14:08:17","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/07\/03\/mas-de-100-pasajeros-se-enferman-de-norovirus-en-crucero-que-volvio-a-san-francisco\/"},"modified":"2026-07-03T20:08:18","modified_gmt":"2026-07-03T20:08:18","slug":"mas-de-100-pasajeros-se-enferman-de-norovirus-en-crucero-que-volvio-a-san-francisco","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/07\/03\/mas-de-100-pasajeros-se-enferman-de-norovirus-en-crucero-que-volvio-a-san-francisco\/","title":{"rendered":"M\u00e1s de 100 pasajeros se enferman de norovirus en crucero que volvi\u00f3 a San Francisco"},"content":{"rendered":"<p>Un crucero de Princess Cruises, el Ruby Princess, regres\u00f3 este jueves 2 de julio al puerto de San Francisco con m\u00e1s de 100 personas contagiadas de norovirus. El barco llevaba a bordo a unos 3 mil pasajeros y 1,144 tripulantes.  <\/p>\n<p>El viaje empez\u00f3 el 12 de junio y dur\u00f3 20 d\u00edas. Durante el trayecto, los pasajeros empezaron a reportar s\u00edntomas gastrointestinales leves, como v\u00f3mitos y diarrea, pero ninguno requiri\u00f3 hospitalizaci\u00f3n.  <\/p>\n<p>Seg\u00fan los CDC, al menos 102 pasajeros y 23 tripulantes presentaron s\u00edntomas relacionados con el norovirus, un virus s\u00faper contagioso que es la principal causa de gastroenteritis en Estados Unidos. Cada a\u00f1o se registran alrededor de 2,500 brotes en el pa\u00eds, la mayor\u00eda por contacto directo entre personas infectadas.  <\/p>\n<p>Despu\u00e9s de llegar a San Francisco, el Ruby Princess fue limpiado y desinfectado para poder zarpar en su siguiente viaje esa misma tarde.  <\/p>\n<p>Este brote se suma a otros detectados en cruceros este a\u00f1o, que han puesto en jaque a la industria y obligado a cuarentenas masivas. Aunque suena alarmante, la r\u00e1pida respuesta y protocolos de limpieza ayudan a mantener el orden y la seguridad en estos viajes.  <\/p>\n<p>Esto es lo que necesitas saber: el norovirus es un fastidio, pero con medidas claras y responsabilidad, los cruceros siguen siendo una opci\u00f3n viable para viajar y disfrutar sin perder el control.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un crucero de Princess Cruises, el Ruby Princess, regres\u00f3 este jueves 2 de julio al puerto de San Francisco con m\u00e1s de 100 personas contagiadas de norovirus. El barco llevaba a bordo a unos 3 mil pasajeros y 1,144 tripulantes. El viaje empez\u00f3 el 12 de junio y dur\u00f3 20 d\u00edas. Durante el trayecto, los&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3132"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3132\/revisions"}],"predecessor-version":[{"id":3133,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3132\/revisions\/3133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/3131"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}