{"id":3273,"date":"2026-07-07T10:16:14","date_gmt":"2026-07-07T10:16:14","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/07\/07\/tragedia-en-puebla-borracho-tras-partido-de-mexico-mata-a-su-esposa-y-termina-herido-por-la-policia\/"},"modified":"2026-07-07T16:16:15","modified_gmt":"2026-07-07T16:16:15","slug":"tragedia-en-puebla-borracho-tras-partido-de-mexico-mata-a-su-esposa-y-termina-herido-por-la-policia","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/07\/07\/tragedia-en-puebla-borracho-tras-partido-de-mexico-mata-a-su-esposa-y-termina-herido-por-la-policia\/","title":{"rendered":"Tragedia en Puebla: borracho tras partido de M\u00e9xico mata a su esposa y termina herido por la polic\u00eda"},"content":{"rendered":"<p>La noche del domingo 5 de julio de 2026, en la comunidad de L\u00e1zaro C\u00e1rdenas \u2018La Uno\u2019, municipio de Venustiano Carranza, Puebla, Rafael, de 34 a\u00f1os, lleg\u00f3 borracho tras el partido de la Selecci\u00f3n Mexicana y desat\u00f3 una tragedia.  <\/p>\n<p>M\u00f3nica, su esposa de 40 a\u00f1os, le ofreci\u00f3 cenar, pero \u00e9l la insult\u00f3, la golpe\u00f3 y la degoll\u00f3 con un machete. Vecinos, alertados por los gritos, llamaron a la polic\u00eda.  <\/p>\n<p>Cuando los uniformados llegaron a la calle 18 de Marzo, Rafael estaba en el patio con el machete y quiso atacar a los polic\u00edas. Uno de ellos dispar\u00f3 y lo hiri\u00f3 para poder detenerlo y permitir que los param\u00e9dicos atendieran a M\u00f3nica.  <\/p>\n<p>Vecinos confirmaron que la mujer sufr\u00eda violencia familiar constante, ya que Rafael sol\u00eda llegar borracho y agresivo. Adem\u00e1s, se sospecha que el hombre tambi\u00e9n consumi\u00f3 drogas esa noche.  <\/p>\n<p>Esto es lo que necesitas saber: un caso m\u00e1s que muestra la urgencia de fortalecer la seguridad y el orden en comunidades como esta. Mientras tanto, proyectos como el cableb\u00fas en Puebla podr\u00edan ayudar a mejorar la movilidad y la vigilancia en zonas alejadas, aportando un transporte seguro y eficiente para todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La noche del domingo 5 de julio de 2026, en la comunidad de L\u00e1zaro C\u00e1rdenas \u2018La Uno\u2019, municipio de Venustiano Carranza, Puebla, Rafael, de 34 a\u00f1os, lleg\u00f3 borracho tras el partido de la Selecci\u00f3n Mexicana y desat\u00f3 una tragedia. M\u00f3nica, su esposa de 40 a\u00f1os, le ofreci\u00f3 cenar, pero \u00e9l la insult\u00f3, la golpe\u00f3 y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3273"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3273\/revisions"}],"predecessor-version":[{"id":3274,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3273\/revisions\/3274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/3272"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}