{"id":3285,"date":"2026-07-07T10:33:08","date_gmt":"2026-07-07T10:33:08","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/07\/07\/los-tuneles-de-la-piramide-de-cholula-vuelven-a-la-vida-tras-6-anos-cerrados\/"},"modified":"2026-07-07T16:33:10","modified_gmt":"2026-07-07T16:33:10","slug":"los-tuneles-de-la-piramide-de-cholula-vuelven-a-la-vida-tras-6-anos-cerrados","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/07\/07\/los-tuneles-de-la-piramide-de-cholula-vuelven-a-la-vida-tras-6-anos-cerrados\/","title":{"rendered":"Los t\u00faneles de la Pir\u00e1mide de Cholula vuelven a la vida tras 6 a\u00f1os cerrados"},"content":{"rendered":"<p>Despu\u00e9s de estar cerrados desde marzo de 2020, los t\u00faneles de la Pir\u00e1mide de Cholula reabrir\u00e1n a finales de julio de 2026. As\u00ed lo confirm\u00f3 Tonantzin Fern\u00e1ndez, presidenta municipal de San Pedro Cholula, justo despu\u00e9s de la presentaci\u00f3n de la Feria del Molote 2026.  <\/p>\n<p>La pandemia fue la raz\u00f3n del cierre, pero ahora, con el apoyo del INAH y la Secretar\u00eda de Desarrollo Tur\u00edstico, las cosas avanzan para que este ic\u00f3nico atractivo regrese a la vida. Adem\u00e1s, la alcaldesa agradeci\u00f3 el respaldo de Claudia Sheinbaum, quien aport\u00f3 recursos extraordinarios para este y otros 40 sitios arqueol\u00f3gicos en el pa\u00eds.  <\/p>\n<p>La administraci\u00f3n local tambi\u00e9n pondr\u00e1 un mill\u00f3n y medio de pesos para mejorar la zona tur\u00edstica, buscando que m\u00e1s visitantes lleguen y que la econom\u00eda local se reactive con fuerza.  <\/p>\n<p>\u00bfLo bueno? Los t\u00faneles estar\u00e1n abiertos de mi\u00e9rcoles a domingo, de 9 a 5 de la tarde, con un costo aproximado de 210 pesos para extranjeros y 105 para nacionales. Aunque a\u00fan no es oficial, conviene seguir las redes del Ayuntamiento y del INAH para no perder detalle.  <\/p>\n<p>Esto es lo que necesitas saber: la reapertura de los t\u00faneles no solo es un plus para el turismo, sino un impulso para las familias cholultecas que viven del comercio local. Un paso firme para que la historia y la econom\u00eda caminen de la mano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de estar cerrados desde marzo de 2020, los t\u00faneles de la Pir\u00e1mide de Cholula reabrir\u00e1n a finales de julio de 2026. As\u00ed lo confirm\u00f3 Tonantzin Fern\u00e1ndez, presidenta municipal de San Pedro Cholula, justo despu\u00e9s de la presentaci\u00f3n de la Feria del Molote 2026. La pandemia fue la raz\u00f3n del cierre, pero ahora, con el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3284,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3285"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3285\/revisions"}],"predecessor-version":[{"id":3286,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3285\/revisions\/3286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/3284"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}