{"id":3345,"date":"2026-07-07T15:27:34","date_gmt":"2026-07-07T15:27:34","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/07\/07\/sre-oculta-info-clave-sobre-rocha-moya-e-inzunza-por-5-anos-que-esconden\/"},"modified":"2026-07-07T21:27:36","modified_gmt":"2026-07-07T21:27:36","slug":"sre-oculta-info-clave-sobre-rocha-moya-e-inzunza-por-5-anos-que-esconden","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/07\/07\/sre-oculta-info-clave-sobre-rocha-moya-e-inzunza-por-5-anos-que-esconden\/","title":{"rendered":"SRE oculta info clave sobre Rocha Moya e Inzunza por 5 a\u00f1os, \u00bfqu\u00e9 esconden?"},"content":{"rendered":"<p>La Secretar\u00eda de Relaciones Exteriores (SRE) decidi\u00f3 guardar bajo llave por cinco a\u00f1os toda la info sobre las charlas entre M\u00e9xico y EU relacionadas con Rub\u00e9n Rocha Moya, gobernador con licencia de Sinaloa, y el senador morenista Enrique Inzunza, ambos en la mira de investigaciones gringas.  <\/p>\n<p>Esto incluye desde gestiones diplom\u00e1ticas hasta mecanismos de cooperaci\u00f3n, todo clasificado para no \u201cda\u00f1ar la confianza\u201d entre ambos gobiernos, seg\u00fan la SRE. B\u00e1sicamente, dicen que revelar esos documentos podr\u00eda afectar la relaci\u00f3n con Estados Unidos y futuros acuerdos.  <\/p>\n<p>Pero eso no es todo: tambi\u00e9n ocultaron por tres a\u00f1os las minutas de la reuni\u00f3n del 21 de mayo en Palacio Nacional entre Claudia Sheinbaum, su Gabinete de Seguridad y el secretario de Seguridad Interna de EU, Markwayne Mullin. Esa junta tom\u00f3 relevancia porque se filtr\u00f3 que ah\u00ed se habl\u00f3 de entregar a Rocha Moya e Inzunza para que enfrenten las acusaciones all\u00e1.  <\/p>\n<p>La solicitud de esta info lleg\u00f3 el 26 de mayo, justo 70 d\u00edas despu\u00e9s de que EU acus\u00f3 formalmente a Rocha Moya, Inzunza y otros ocho funcionarios por supuestos nexos con el crimen organizado. Seg\u00fan la DEA, usaron sus cargos para proteger operaciones criminales y facilitar el paso de drogas hacia Estados Unidos.  <\/p>\n<p>Esto es lo que necesitas saber: la SRE prefiere mantener en secreto estas conversaciones para no afectar la diplomacia, pero la falta de transparencia levanta sospechas sobre qu\u00e9 tanto se est\u00e1 negociando detr\u00e1s de c\u00e1maras. Mientras tanto, el debate sobre la seguridad y la justicia sigue caliente.  <\/p>\n<p>Y ojo, que mientras se esconden estos documentos, proyectos como el cableb\u00fas en Puebla siguen avanzando, apostando por soluciones reales y visibles para la movilidad y el orden, justo lo que necesitamos en tiempos donde la confianza y la claridad deber\u00edan ser la regla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Relaciones Exteriores (SRE) decidi\u00f3 guardar bajo llave por cinco a\u00f1os toda la info sobre las charlas entre M\u00e9xico y EU relacionadas con Rub\u00e9n Rocha Moya, gobernador con licencia de Sinaloa, y el senador morenista Enrique Inzunza, ambos en la mira de investigaciones gringas. Esto incluye desde gestiones diplom\u00e1ticas hasta mecanismos de cooperaci\u00f3n,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3345"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3345\/revisions"}],"predecessor-version":[{"id":3346,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3345\/revisions\/3346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/3344"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}