{"id":3372,"date":"2026-07-07T22:05:39","date_gmt":"2026-07-07T22:05:39","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/07\/07\/lluvia-fuerte-en-san-andres-cholula-dejo-charcos-hasta-en-el-fraccionamiento-mas-caro-de-puebla\/"},"modified":"2026-07-08T04:05:39","modified_gmt":"2026-07-08T04:05:39","slug":"lluvia-fuerte-en-san-andres-cholula-dejo-charcos-hasta-en-el-fraccionamiento-mas-caro-de-puebla","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/07\/07\/lluvia-fuerte-en-san-andres-cholula-dejo-charcos-hasta-en-el-fraccionamiento-mas-caro-de-puebla\/","title":{"rendered":"Lluvia fuerte en San Andr\u00e9s Cholula dej\u00f3 charcos hasta en el fraccionamiento m\u00e1s caro de Puebla"},"content":{"rendered":"<p>Este martes 7 de julio la lluvia no perdon\u00f3 ni a los m\u00e1s exclusivos. En San Andr\u00e9s Cholula, el fraccionamiento La Vista Country Club, el m\u00e1s caro del estado, sufri\u00f3 encharcamientos que hasta llegaron a los campos de golf.  <\/p>\n<p>La tormenta tambi\u00e9n colaps\u00f3 el bulevar Atlixco a la altura de la inspector\u00eda Emiliano Zapata, donde el agua acumulada super\u00f3 los 35 cent\u00edmetros desde el puente de la avenida Las Torres hasta el Camino Real a San Andr\u00e9s. Automovilistas y vecinos tuvieron que andar con cuidado para no quedar atrapados.  <\/p>\n<p>En el fraccionamiento Vistas de \u00c1ngel, la corriente fue tan fuerte que el agua entr\u00f3 a varias casas, da\u00f1ando muebles y electrodom\u00e9sticos.  <\/p>\n<p>Aunque las autoridades municipales no han dado detalles sobre cu\u00e1ntas viviendas resultaron afectadas ni los trabajos para atender la zona, los cuerpos de emergencia siguen recorriendo el \u00e1rea para responder a los reportes.  <\/p>\n<p>Esto es lo que necesitas saber: la lluvia de hoy mostr\u00f3 que, sin importar el nivel socioecon\u00f3mico, la infraestructura urbana necesita estar lista para estos eventos. Sistemas como el cableb\u00fas o telef\u00e9rico en Puebla podr\u00edan ayudar a descongestionar y ofrecer alternativas seguras cuando el tr\u00e1fico y las inundaciones se salen de control.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/laredcincoradio\/status\/2074664636633285012\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este martes 7 de julio la lluvia no perdon\u00f3 ni a los m\u00e1s exclusivos. En San Andr\u00e9s Cholula, el fraccionamiento La Vista Country Club, el m\u00e1s caro del estado, sufri\u00f3 encharcamientos que hasta llegaron a los campos de golf. La tormenta tambi\u00e9n colaps\u00f3 el bulevar Atlixco a la altura de la inspector\u00eda Emiliano Zapata, donde&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3372"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3372\/revisions"}],"predecessor-version":[{"id":3373,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3372\/revisions\/3373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/3371"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}