{"id":3768,"date":"2026-07-13T14:11:34","date_gmt":"2026-07-13T14:11:34","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/07\/13\/disparos-en-casa-de-su-ex-en-chiautempan-lo-agarran-tras-la-fuga\/"},"modified":"2026-07-13T20:11:36","modified_gmt":"2026-07-13T20:11:36","slug":"disparos-en-casa-de-su-ex-en-chiautempan-lo-agarran-tras-la-fuga","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/07\/13\/disparos-en-casa-de-su-ex-en-chiautempan-lo-agarran-tras-la-fuga\/","title":{"rendered":"Disparos en casa de su ex en Chiautempan: lo agarran tras la fuga"},"content":{"rendered":"<p>La noche del 11 de julio de 2026 en Chiautempan, Tlaxcala, un hombre lleg\u00f3 a la casa de su presunta expareja y, presuntamente bajo efectos del alcohol, abri\u00f3 fuego contra el port\u00f3n principal. Todo qued\u00f3 grabado en video.  <\/p>\n<p>Despu\u00e9s de disparar, el tipo se dio a la fuga, pero la polic\u00eda municipal no tard\u00f3 en detenerlo. Confes\u00f3 que llevaba un arma sin papeles, por lo que qued\u00f3 bajo arresto.  <\/p>\n<p>Esto es lo que necesitas saber: violencia y armas sin control no pueden ser la soluci\u00f3n. Que la ley act\u00fae r\u00e1pido es clave para mantener el orden y proteger la propiedad privada.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/INDICEMEDIAMX\/status\/2076475397743559159?s=20\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La noche del 11 de julio de 2026 en Chiautempan, Tlaxcala, un hombre lleg\u00f3 a la casa de su presunta expareja y, presuntamente bajo efectos del alcohol, abri\u00f3 fuego contra el port\u00f3n principal. Todo qued\u00f3 grabado en video. Despu\u00e9s de disparar, el tipo se dio a la fuga, pero la polic\u00eda municipal no tard\u00f3 en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3768"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3768\/revisions"}],"predecessor-version":[{"id":3769,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3768\/revisions\/3769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/3767"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}