{"id":3861,"date":"2026-07-14T11:33:19","date_gmt":"2026-07-14T11:33:19","guid":{"rendered":"https:\/\/zource.mx\/index.php\/2026\/07\/14\/empresario-espanol-ligado-a-ataques-armados-en-via-atlixcayotl-fue-detenido-hoy-en-puebla\/"},"modified":"2026-07-14T17:33:21","modified_gmt":"2026-07-14T17:33:21","slug":"empresario-espanol-ligado-a-ataques-armados-en-via-atlixcayotl-fue-detenido-hoy-en-puebla","status":"publish","type":"post","link":"https:\/\/zource.mx\/index.php\/2026\/07\/14\/empresario-espanol-ligado-a-ataques-armados-en-via-atlixcayotl-fue-detenido-hoy-en-puebla\/","title":{"rendered":"Empresario espa\u00f1ol ligado a ataques armados en V\u00eda Atlixc\u00e1yotl fue detenido hoy en Puebla"},"content":{"rendered":"<p>Este martes 14 de julio, Rafael Zabalza Veraza, empresario farmac\u00e9utico y due\u00f1o de una gasolinera en Puebla, fue arrestado en un operativo en Santa Fe, Angel\u00f3polis. La Fiscal\u00eda, Polic\u00eda Estatal, Guardia Nacional, Ej\u00e9rcito y Marina participaron en la captura, que se complic\u00f3 porque Zabalza dispar\u00f3 contra los agentes antes de ser detenido.  <\/p>\n<p>Adem\u00e1s de su negocio farmac\u00e9utico, Zabalza es propietario de Grupo Emprendedor Gasolinero, S.A. de C.V., con domicilio en la colonia Bella Vista. Tambi\u00e9n ha sido vinculado a un ataque armado previo contra una tienda Telcel en Plaza V\u00eda San \u00c1ngel, aunque esa acusaci\u00f3n a\u00fan no tiene resoluci\u00f3n oficial.  <\/p>\n<p>Por si fuera poco, este empresario ha sido proveedor de medicamentos y equipo m\u00e9dico en gobiernos estatales pasados y recientemente firm\u00f3 un convenio con la Universidad Polit\u00e9cnica Metropolitana de Puebla a trav\u00e9s de la asociaci\u00f3n civil ITEBIO A.C.  <\/p>\n<p>La Fiscal\u00eda sigue investigando su posible relaci\u00f3n con los ataques armados contra automovilistas en la V\u00eda Atlixc\u00e1yotl y otros hechos relacionados. Mientras tanto, la seguridad en esa zona sigue siendo prioridad para evitar que estos episodios afecten la movilidad y tranquilidad de los poblanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes 14 de julio, Rafael Zabalza Veraza, empresario farmac\u00e9utico y due\u00f1o de una gasolinera en Puebla, fue arrestado en un operativo en Santa Fe, Angel\u00f3polis. La Fiscal\u00eda, Polic\u00eda Estatal, Guardia Nacional, Ej\u00e9rcito y Marina participaron en la captura, que se complic\u00f3 porque Zabalza dispar\u00f3 contra los agentes antes de ser detenido. Adem\u00e1s de su&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3860,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","article","has-excerpt","has-avatar","has-author","has-date","has-comment-count","has-category-meta","has-read-more","has-title","has-post-media","thumbnail-"],"_links":{"self":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3861"}],"version-history":[{"count":1,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3861\/revisions"}],"predecessor-version":[{"id":3862,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/posts\/3861\/revisions\/3862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media\/3860"}],"wp:attachment":[{"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zource.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}